{"id":703,"date":"2024-02-13T15:52:51","date_gmt":"2024-02-13T15:52:51","guid":{"rendered":"https:\/\/regiontchologo.ci\/?p=703"},"modified":"2024-02-13T15:52:53","modified_gmt":"2024-02-13T15:52:53","slug":"activites-du-mardi-gras-fevrier-2024-des-maternelles-de-liepp-ferke-sud","status":"publish","type":"post","link":"https:\/\/regiontchologo.ci\/index.php\/2024\/02\/13\/activites-du-mardi-gras-fevrier-2024-des-maternelles-de-liepp-ferke-sud\/","title":{"rendered":"ACTIVIT\u00c9S DU MARDI GRAS F\u00c9VRIER 2024 DES MATERNELLES DE L&rsquo;IEPP FERKE SUD"},"content":{"rendered":"\n<p>Mardi 13 f\u00e9vrier 2024 , le mardi gras, annon\u00e7ant le saint mois du car\u00eame catholique a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9 par la Maternelle du quartier R\u00e9sidentiel. Et comme chaque ann\u00e9e, le Conseil R\u00e9gional du Tchologo a re\u00e7u la visite des tout-petits de ladite maternelle sous le coup de 10 heures GMT.<br>L&rsquo;ensemble du personnel dudit Conseil R\u00e9gional avec \u00e0 sa t\u00eate le DGA Monsieur COULIBALY Moussa Noubonvon a communi\u00e9 avec ces enfants qui n&rsquo;ont pas manqu\u00e9 de partager leur joie et leur bonheur avec leurs h\u00f4tes du jour.<br>Il est bon de noter demain mercredi 14 f\u00e9vrier 2024, mercredi des Cendres, d\u00e9marrent les activit\u00e9s du mois Pascal.<br>Dimanche 24 mars, Dimanche des Rameaux, le Jeudi 28 mars ( jeudi Saint), vendredi 29 mars (vendredi Saint), samedi 30 mars (samedi Saint) et dimanche 31 mars (Jour de la c\u00e9l\u00e9bration de la P\u00e2ques).<br>Bonne et Sainte pr\u00e9paration \u00e0 toutes et \u00e0 tous.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"705\" src=\"https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-705\" srcset=\"https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-1-1024x576.jpeg 1024w, https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-1-300x169.jpeg 300w, https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-1-768x432.jpeg 768w, https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-1.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"706\" src=\"https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-1024x576.jpeg\" alt=\"\" class=\"wp-image-706\" srcset=\"https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-1024x576.jpeg 1024w, https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-300x169.jpeg 300w, https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25-768x432.jpeg 768w, https:\/\/regiontchologo.ci\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-13-at-15.38.25.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mardi 13 f\u00e9vrier 2024 , le mardi gras, annon\u00e7ant le saint mois du car\u00eame catholique<\/p>\n","protected":false},"author":1,"featured_media":704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites"],"_links":{"self":[{"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/posts\/703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/comments?post=703"}],"version-history":[{"count":1,"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/posts\/703\/revisions"}],"predecessor-version":[{"id":707,"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/posts\/703\/revisions\/707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/media\/704"}],"wp:attachment":[{"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/media?parent=703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/categories?post=703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regiontchologo.ci\/index.php\/wp-json\/wp\/v2\/tags?post=703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}